{"id":12009,"date":"2024-08-07T03:19:02","date_gmt":"2024-08-07T01:19:02","guid":{"rendered":"https:\/\/culturasconstructivas.org\/resultados-da-escola-de-verao-iberica-2024\/"},"modified":"2024-10-02T19:15:40","modified_gmt":"2024-10-02T17:15:40","slug":"resultados-da-escola-de-verao-iberica-2024","status":"publish","type":"post","link":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/","title":{"rendered":"Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12009\" class=\"elementor elementor-12009 elementor-11912\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e59832 e-flex e-con-boxed e-con e-parent\" data-id=\"4e59832\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c40d48 elementor-widget elementor-widget-text-editor\" data-id=\"8c40d48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Escola de Ver\u00e3o Ib\u00e9rica teve lugar de 8 a 21 de julho de 2024 em Arcos de Valdevez, no norte de Portugal.<\/p>\n<p>O programa foi organizado pela Funda\u00e7\u00e3o Culturas Construtivas Tradicionais com a colabora\u00e7\u00e3o do INTBAU Portugal e do INTBAU Espanha; gra\u00e7as ao apoio de Richard H. Driehaus, do Munic\u00edpio de Arcos de Valdevez, da Funda\u00e7\u00e3o Serra Henriques, da Kalam, de Robert Adam, da Funda\u00e7\u00e3o Arquia e do King\u2019s Trust Australia; e \u00e0 colabora\u00e7\u00e3o das escolas de arquitetura da Universidade de Notre Dame, da Universidade de Miami, da Universidade do Porto, da Universidade Portucalense, da Universidade Polit\u00e9cnica de Madrid e do Centro de Investiga\u00e7\u00e3o de Arquitetura Tradicional (CIAT), bem como de outras institui\u00e7\u00f5es como Apatrigal, a Rede Horrea, Friol e a Carpintaria Senhora da Paz.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9af4952 e-flex e-con-boxed e-con e-parent\" data-id=\"9af4952\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-174a5a0 e-con-full e-flex e-con e-child\" data-id=\"174a5a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dd51d3 elementor-widget elementor-widget-image\" data-id=\"2dd51d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos2.jpg\" class=\"attachment-large size-large wp-image-11918\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos2.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos2-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc6e7e6 e-con-full e-flex e-con e-child\" data-id=\"bc6e7e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9ddcd7 elementor-widget elementor-widget-image\" data-id=\"c9ddcd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos3.jpg\" class=\"attachment-large size-large wp-image-11921\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos3.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos3-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fafc4c0 e-flex e-con-boxed e-con e-parent\" data-id=\"fafc4c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3085662 elementor-widget elementor-widget-heading\" data-id=\"3085662\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u2013 O Local \u2013<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3577fca e-flex e-con-boxed e-con e-parent\" data-id=\"3577fca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7669532 elementor-widget elementor-widget-text-editor\" data-id=\"7669532\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A escola de ver\u00e3o foi realizada na Peneda, no Santu\u00e1rio de Nossa Senhora da Peneda, localizado na freguesia de Gavieira, munic\u00edpio de Arcos de Valdevez, Portugal, muito perto da fronteira com a Espanha. O Santu\u00e1rio est\u00e1 situado dentro do Parque Nacional da Peneda-Ger\u00eas. <\/p>\n<p>O Santu\u00e1rio de Nossa Senhora da Peneda \u00e9 um importante local de peregrina\u00e7\u00e3o, conhecido pela sua impressionante escadaria de granito que sobe at\u00e9 \u00e0 igreja. A constru\u00e7\u00e3o do santu\u00e1rio come\u00e7ou no s\u00e9culo XVIII e tem sido um ponto central para a devo\u00e7\u00e3o mariana na regi\u00e3o. Al\u00e9m disso, s\u00e3o caracter\u00edsticos desta regi\u00e3o os <em>espigueiros<\/em> de pedra e madeira, que s\u00e3o utilizados para o armazenamento de gr\u00e3os.  <\/p>\n<p>Embora o grupo tenha ficado hospedado na Peneda, onde grande parte do programa teve lugar, v\u00e1rios locais do munic\u00edpio de Arcos de Valdevez tamb\u00e9m foram visitados, estudados e desenhados: Soajo, S\u00e3o Bento do Cando, Branda de Santo Ant\u00f3nio, Sistelo e Padr\u00e3o.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67c1c38 e-flex e-con-boxed e-con e-parent\" data-id=\"67c1c38\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4324a4a e-con-full e-flex e-con e-child\" data-id=\"4324a4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef7989a elementor-widget elementor-widget-image\" data-id=\"ef7989a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos4.jpg\" class=\"attachment-large size-large wp-image-11924\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos4.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos4-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c84e25 e-con-full e-flex e-con e-child\" data-id=\"0c84e25\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e164bd1 elementor-widget elementor-widget-image\" data-id=\"e164bd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos5.jpg\" class=\"attachment-large size-large wp-image-11927\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos5.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos5-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8179f0 e-con-full e-flex e-con e-child\" data-id=\"c8179f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2b7442 elementor-widget elementor-widget-image\" data-id=\"d2b7442\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos6.jpg\" class=\"attachment-large size-large wp-image-11930\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos6.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos6-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b815ccf e-con-full e-flex e-con e-child\" data-id=\"b815ccf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e421aa elementor-widget elementor-widget-image\" data-id=\"5e421aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos7.jpg\" class=\"attachment-large size-large wp-image-11933\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos7.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos7-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26ad8dd e-flex e-con-boxed e-con e-parent\" data-id=\"26ad8dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59558b elementor-widget elementor-widget-heading\" data-id=\"b59558b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u2013 O Processo de Trabalho \u2013<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-514d114 e-flex e-con-boxed e-con e-parent\" data-id=\"514d114\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72870d5 elementor-widget elementor-widget-text-editor\" data-id=\"72870d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O programa centrou-se no estudo do urbanismo, da arquitetura e dos detalhes de constru\u00e7\u00e3o tradicionais da regi\u00e3o, principalmente atrav\u00e9s do desenho \u00e0 m\u00e3o. Procurava-se com isso que os participantes se familiarizassem com o car\u00e1ter e as qualidades da arquitetura da regi\u00e3o. Especialistas em arquitetura vern\u00e1cula local, paisagem e t\u00e9cnicas de constru\u00e7\u00e3o deram palestras e realizaram diversos workshops sobre temas relacionados. Durante a primeira semana, foram organizadas v\u00e1rias viagens pela regi\u00e3o, que permitiram estudar e desenhar a arquitetura local de diversos locais. Na segunda semana, com base no trabalho realizado anteriormente, os estudantes trabalharam em grupo numa proposta de design urbano para a Peneda. O processo tamb\u00e9m envolveu os habitantes locais, a fim de adaptar a proposta \u00e0s suas necessidades.     <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48a55d6 e-flex e-con-boxed e-con e-parent\" data-id=\"48a55d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-972ab75 e-con-full e-flex e-con e-child\" data-id=\"972ab75\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebf8d24 elementor-widget elementor-widget-image\" data-id=\"ebf8d24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos8.jpg\" class=\"attachment-large size-large wp-image-11936\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos8.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos8-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fce1a84 e-con-full e-flex e-con e-child\" data-id=\"fce1a84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7853c90 elementor-widget elementor-widget-image\" data-id=\"7853c90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos9.jpg\" class=\"attachment-large size-large wp-image-11939\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos9.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos9-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcf339a e-con-full e-flex e-con e-child\" data-id=\"bcf339a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aba549d elementor-widget elementor-widget-image\" data-id=\"aba549d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos10.jpg\" class=\"attachment-large size-large wp-image-11942\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos10.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos10-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99855bb e-con-full e-flex e-con e-child\" data-id=\"99855bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85485a8 elementor-widget elementor-widget-image\" data-id=\"85485a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos11.jpg\" class=\"attachment-large size-large wp-image-11945\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos11.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos11-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c3476b2 e-flex e-con-boxed e-con e-parent\" data-id=\"c3476b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d695e9 elementor-widget elementor-widget-heading\" data-id=\"5d695e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u2013 A proposta de interven\u00e7\u00e3o \u2013<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a91daa e-flex e-con-boxed e-con e-parent\" data-id=\"4a91daa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86b10c1 elementor-widget elementor-widget-text-editor\" data-id=\"86b10c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Com base neste trabalho inicial, e respondendo tamb\u00e9m \u00e0s necessidades apresentadas pelos habitantes da Peneda, foi elaborada, com a colabora\u00e7\u00e3o de todos os participantes da escola de ver\u00e3o, uma proposta para a melhoria do entorno do Santu\u00e1rio de Nossa Senhora da Peneda, bem como do seu acesso e da sua liga\u00e7\u00e3o ao vale. Al\u00e9m disso, foram propostas v\u00e1rias interven\u00e7\u00f5es na Peneda, de diversas escalas e naturezas, abrangendo desde a reconfigura\u00e7\u00e3o urbana at\u00e9 a atua\u00e7\u00e3o em v\u00e1rias habita\u00e7\u00f5es. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ba9f52 e-flex e-con-boxed e-con e-parent\" data-id=\"8ba9f52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b95af6d elementor-widget elementor-widget-image\" data-id=\"b95af6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"406\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos17-1024x520.jpg\" class=\"attachment-large size-large wp-image-11963\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos17-1024x520.jpg 1024w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos17-300x152.jpg 300w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos17-768x390.jpg 768w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos17-1536x780.jpg 1536w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos17.jpg 1746w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0a24295 e-flex e-con-boxed e-con e-parent\" data-id=\"0a24295\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71123d3 elementor-widget elementor-widget-image\" data-id=\"71123d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"325\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos18-1024x416.jpg\" class=\"attachment-large size-large wp-image-11966\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos18-1024x416.jpg 1024w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos18-300x122.jpg 300w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos18-768x312.jpg 768w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos18-1536x624.jpg 1536w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos18.jpg 1603w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dd0d9e2 e-flex e-con-boxed e-con e-parent\" data-id=\"dd0d9e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9f0279f e-con-full e-flex e-con e-child\" data-id=\"9f0279f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ac1e4c elementor-widget elementor-widget-image\" data-id=\"6ac1e4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"565\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos19-1024x723.jpg\" class=\"attachment-large size-large wp-image-11969\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos19-1024x723.jpg 1024w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos19-300x212.jpg 300w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos19-768x542.jpg 768w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos19.jpg 1234w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f554d36 e-con-full e-flex e-con e-child\" data-id=\"f554d36\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd533e2 elementor-widget elementor-widget-image\" data-id=\"cd533e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"439\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos20-1024x562.jpg\" class=\"attachment-large size-large wp-image-11972\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos20-1024x562.jpg 1024w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos20-300x165.jpg 300w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos20-768x422.jpg 768w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos20.jpg 1248w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef14b11 e-con-full e-flex e-con e-child\" data-id=\"ef14b11\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17de9c3 elementor-widget elementor-widget-image\" data-id=\"17de9c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"609\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos21-1024x779.jpg\" class=\"attachment-large size-large wp-image-11975\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos21-1024x779.jpg 1024w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos21-300x228.jpg 300w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos21-768x584.jpg 768w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos21.jpg 1107w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f728ca e-con-full e-flex e-con e-child\" data-id=\"5f728ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-946f73f elementor-widget elementor-widget-image\" data-id=\"946f73f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"544\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos22-1024x696.jpg\" class=\"attachment-large size-large wp-image-11978\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos22-1024x696.jpg 1024w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos22-300x204.jpg 300w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos22-768x522.jpg 768w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos22.jpg 1210w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a2c85a e-flex e-con-boxed e-con e-parent\" data-id=\"9a2c85a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbdeba3 elementor-widget elementor-widget-heading\" data-id=\"cbdeba3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u2013 Resultados e exposi\u00e7\u00e3o \u2013<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fffcb8 e-flex e-con-boxed e-con e-parent\" data-id=\"1fffcb8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bcc1f4f elementor-widget elementor-widget-text-editor\" data-id=\"bcc1f4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tanto o trabalho de documenta\u00e7\u00e3o inicial quanto a proposta de design final foram expostos publicamente ao final da escola de ver\u00e3o na Biblioteca Tomaz Figueiredo, em Arcos de Valdevez. A exposi\u00e7\u00e3o \u2013 \u00e0 qual compareceram, entre outros, o presidente da c\u00e2mara e v\u00e1rios representantes do munic\u00edpio de Arcos de Valdevez \u2013 foi seguida de uma celebra\u00e7\u00e3o de encerramento na Peneda, na qual participou grande parte da popula\u00e7\u00e3o local. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b7236b e-flex e-con-boxed e-con e-parent\" data-id=\"3b7236b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bc578c7 e-con-full e-flex e-con e-child\" data-id=\"bc578c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53b2b45 elementor-widget elementor-widget-image\" data-id=\"53b2b45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos12.jpg\" class=\"attachment-large size-large wp-image-11948\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos12.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos12-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a8281f e-con-full e-flex e-con e-child\" data-id=\"7a8281f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-976c3ef elementor-widget elementor-widget-image\" data-id=\"976c3ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos13.jpg\" class=\"attachment-large size-large wp-image-11951\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos13.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos13-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67d65b7 e-flex e-con-boxed e-con e-parent\" data-id=\"67d65b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8dd94a elementor-widget elementor-widget-heading\" data-id=\"e8dd94a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u2013 Outras atividades \u2013<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-165830a e-flex e-con-boxed e-con e-parent\" data-id=\"165830a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e5477f7 e-con-full e-flex e-con e-child\" data-id=\"e5477f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc7154b elementor-widget elementor-widget-image\" data-id=\"cc7154b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos14.jpg\" class=\"attachment-large size-large wp-image-11954\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos14.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos14-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68214f3 e-con-full e-flex e-con e-child\" data-id=\"68214f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8906984 elementor-widget elementor-widget-text-editor\" data-id=\"8906984\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Workshops de t\u00e9cnicas tradicionais de constru\u00e7\u00e3o<\/strong><\/p>\n<p>V\u00e1rios mestres da constru\u00e7\u00e3o tradicional ministraram workshops durante a escola de ver\u00e3o. O mestre pedreiro Guillermo Rodr\u00edguez realizou uma introdu\u00e7\u00e3o pr\u00e1tica ao trabalho manual da pedra; o mestre estucador Marco Aur\u00e9lio realizou uma introdu\u00e7\u00e3o te\u00f3rica e pr\u00e1tica ao seu of\u00edcio; enquanto os mestres carpinteiros da Carpintaria Senhora da Paz realizaram uma demonstra\u00e7\u00e3o sobre os trabalhos de carpintaria caracter\u00edsticos da regi\u00e3o. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-01716f0 e-flex e-con-boxed e-con e-parent\" data-id=\"01716f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-acbcbbb e-con-full e-flex e-con e-child\" data-id=\"acbcbbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce3b648 elementor-widget elementor-widget-image\" data-id=\"ce3b648\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos16.jpg\" class=\"attachment-large size-large wp-image-11960\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos16.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos16-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6972bf8 e-con-full e-flex e-con e-child\" data-id=\"6972bf8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec6375f elementor-widget elementor-widget-text-editor\" data-id=\"ec6375f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Confer\u00eancias<\/strong><\/p>\n<p>Al\u00e9m do trabalho de campo, foram convidados especialistas em urbanismo, hist\u00f3ria da arquitetura, antropologia, paisagem e arquitetura e constru\u00e7\u00e3o tradicionais para dar confer\u00eancias sobre esses temas. As confer\u00eancias foram realizadas no Santu\u00e1rio de Nossa Senhora da Peneda. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6db5511 e-flex e-con-boxed e-con e-parent\" data-id=\"6db5511\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-48176b9 e-con-full e-flex e-con e-child\" data-id=\"48176b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f0303b elementor-widget elementor-widget-image\" data-id=\"8f0303b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"542\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos15.jpg\" class=\"attachment-large size-large wp-image-11957\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos15.jpg 724w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos15-300x225.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2f2efa e-con-full e-flex e-con e-child\" data-id=\"f2f2efa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-353c303 elementor-widget elementor-widget-text-editor\" data-id=\"353c303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Cursos e workshops de desenho<\/strong><\/p>\n<p>V\u00e1rios participantes da escola de ver\u00e3o ministraram diversos workshops de composi\u00e7\u00e3o, desenho, aquarela e outras t\u00e9cnicas pict\u00f3ricas.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e200d47 e-flex e-con-boxed e-con e-parent\" data-id=\"e200d47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77b91a5 elementor-widget elementor-widget-heading\" data-id=\"77b91a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u2013 A equipe organizadora, os professores e os participantes \u2013<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76a1a42 e-flex e-con-boxed e-con e-parent\" data-id=\"76a1a42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4aea2a elementor-widget elementor-widget-text-editor\" data-id=\"b4aea2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A equipe docente e organizadora foi formada por Fernando Cerqueira Barros (Univ. Porto \/ CEAU), Jos\u00e9 Franqueira Baganha (INTBAU Portugal | Funda\u00e7\u00e3o Culturas Construtivas Tradicionais), Alejandro Garc\u00eda Hermida (Univ. Polit\u00e9cnica de Madrid | Funda\u00e7\u00e3o Culturas Construtivas Tradicionais | INTBAU Espanha), Guillermo Gil Fern\u00e1ndez (Funda\u00e7\u00e3o Culturas Construtivas Tradicionais | INTBAU Espanha), Rebeca G\u00f3mez-Gordo Villa (Funda\u00e7\u00e3o Culturas Construtivas Tradicionais | INTBAU Espanha) e Lucas Mart\u00ed Guitera (Funda\u00e7\u00e3o Culturas Construtivas Tradicionais).<\/p>\n<p>Os palestrantes convidados foram Joana Ara\u00fajo (Lantana), Clementina Braga, \u00c1lvaro Campelo (Universidade Fernando Pessoa &#8211; UFP), Gon\u00e7alo Cornelio da Silva, Jorge Dias (Instituto da Conserva\u00e7\u00e3o da Natureza e das Florestas, IP), \u00c1lvaro Domingues (Universidade do Porto FAUP-CEAU), Carlos Henrique Fern\u00e1ndez Coto (Apatrigal | Horrea), Rui Florentino (Universidade Portucalense &#8211; UPT | INTBAU Portugal), C\u00e9sar Maciel (Santu\u00e1rio de Nossa Senhora da Peneda), Ant\u00f3nio Fernandez Medeiros (ISCTE-IUL), Ant\u00f3nio Men\u00e9res (Universidade do Porto FAUP), Goreti Sousa (Universidade Portucalense &#8211; UPT), Alda Rodrigues (Lantana), Alcinda Tavares (Parque Nacional da Peneda-Ger\u00eas), Carlos Eduardo Viana (Associa\u00e7\u00e3o de Produ\u00e7\u00e3o e Anima\u00e7\u00e3o Audiovisual).<\/p>\n<p>E os participantes foram Andr\u00e9s Belderrain Garc\u00eda (Espanha), Teodoro Bueres (EUA), Nataliia Chernobryvets (Ucr\u00e2nia), Ivo Chytil (Rep\u00fablica Checa), Meredith Fairman (EUA), Marta Cristina Follana Delgado (Espanha), Peyton Gable (EUA), Christa Gabrielson (EUA), Ay\u015fe Nur Ger (Turquia), Roc\u00edo G\u00f3mez Llopis (Espanha), Andreea-Larisa H\u0103\u021bi\u0219-Condoiu (Rom\u00eania), Ai-Vi Hoang (EUA), Kalina Jasiak (Pol\u00f4nia | EUA), Eric Kerke (EUA), Margarida Martins Pinhal (Portugal), Nieves Navas Rodr\u00edguez-Camu\u00f1as (Espanha), Manoel Pal\u00e1cios e Cabral de Melo (Portugal), Eva Ribeiro Vaz (Portugal), Miriam Samir Rincon (M\u00e9xico), Paul Schickhofer (\u00c1ustria), \u00c1lvaro Schmitt Vergara (Chile), Ashish Singh Pundir (\u00cdndia), Orlando Mattia Surcel (Austr\u00e1lia), Theano Vachla (Gr\u00e9cia) e Carlos Vallecillos Moya (Espanha).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ad5dba e-flex e-con-boxed e-con e-parent\" data-id=\"1ad5dba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0035f0a elementor-widget elementor-widget-image\" data-id=\"0035f0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"427\" src=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos23-1024x546.jpg\" class=\"attachment-large size-large wp-image-12001\" alt=\"\" srcset=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos23-1024x546.jpg 1024w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos23-300x160.jpg 300w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos23-768x409.jpg 768w, https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos23.jpg 1330w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-847729c e-flex e-con-boxed e-con e-parent\" data-id=\"847729c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b80c31 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7b80c31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/formacao\/escola-de-verao\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mais informa\u00e7\u00f5es sobre as Escolas de Ver\u00e3o<br><br><br><br><br><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A Escola de Ver\u00e3o Ib\u00e9rica teve lugar de 8 a 21 de julho de 2024 em Arcos de Valdevez, no norte de Portugal. O programa foi organizado pela Funda\u00e7\u00e3o Culturas Construtivas Tradicionais com a colabora\u00e7\u00e3o do INTBAU Portugal e do INTBAU Espanha; gra\u00e7as ao apoio de Richard H. Driehaus, do Munic\u00edpio de Arcos de Valdevez, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":11915,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_piecal_is_event":false,"_piecal_start_date":"","_piecal_end_date":"","_piecal_is_allday":false,"footnotes":""},"categories":[93,51],"tags":[],"class_list":["post-12009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escola-verao-arcos-2024","category-escola-de-verao-iberica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024 - Fundaci\u00f3n Culturas Constructivas Tradicionales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024 - Fundaci\u00f3n Culturas Constructivas Tradicionales\" \/>\n<meta property=\"og:description\" content=\"A Escola de Ver\u00e3o Ib\u00e9rica teve lugar de 8 a 21 de julho de 2024 em Arcos de Valdevez, no norte de Portugal. O programa foi organizado pela Funda\u00e7\u00e3o Culturas Construtivas Tradicionais com a colabora\u00e7\u00e3o do INTBAU Portugal e do INTBAU Espanha; gra\u00e7as ao apoio de Richard H. Driehaus, do Munic\u00edpio de Arcos de Valdevez, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Culturas Constructivas Tradicionales\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-07T01:19:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T17:15:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guillermo Gil\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guillermo Gil\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/\"},\"author\":{\"name\":\"Guillermo Gil\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#\\\/schema\\\/person\\\/2cff5e4776f5f0b01b837faf3fdc4664\"},\"headline\":\"Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024\",\"datePublished\":\"2024-08-07T01:19:02+00:00\",\"dateModified\":\"2024-10-02T17:15:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/\"},\"wordCount\":1088,\"publisher\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/EscuelaArcos1.jpg\",\"articleSection\":[\"Escola de Ver\u00e3o Arcos 2024\",\"Escola de Ver\u00e3o Ib\u00e9rica\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/\",\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/\",\"name\":\"Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024 - Fundaci\u00f3n Culturas Constructivas Tradicionales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/EscuelaArcos1.jpg\",\"datePublished\":\"2024-08-07T01:19:02+00:00\",\"dateModified\":\"2024-10-02T17:15:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/EscuelaArcos1.jpg\",\"contentUrl\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/EscuelaArcos1.jpg\",\"width\":724,\"height\":542},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/resultados-da-escola-de-verao-iberica-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/fundacao-culturas-construtivas-tradicionais\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/\",\"name\":\"Fundaci\u00f3n Culturas Constructivas Tradicionales\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#organization\",\"name\":\"Fundaci\u00f3n Culturas Constructivas Tradicionales\",\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/FUNDACAO-CULTURAS-CONSTRUTIVAS-Logo.png\",\"contentUrl\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/FUNDACAO-CULTURAS-CONSTRUTIVAS-Logo.png\",\"width\":537,\"height\":290,\"caption\":\"Fundaci\u00f3n Culturas Constructivas Tradicionales\"},\"image\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#\\\/schema\\\/person\\\/2cff5e4776f5f0b01b837faf3fdc4664\",\"name\":\"Guillermo Gil\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6648e10de371ca3bbb6c2dfc0bd2f680bc092a6a74dfe978fb2fcc2bd9b3c27?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6648e10de371ca3bbb6c2dfc0bd2f680bc092a6a74dfe978fb2fcc2bd9b3c27?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6648e10de371ca3bbb6c2dfc0bd2f680bc092a6a74dfe978fb2fcc2bd9b3c27?s=96&d=mm&r=g\",\"caption\":\"Guillermo Gil\"},\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/author\\\/guillermo-gil\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024 - Fundaci\u00f3n Culturas Constructivas Tradicionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/","og_locale":"pt_PT","og_type":"article","og_title":"Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024 - Fundaci\u00f3n Culturas Constructivas Tradicionales","og_description":"A Escola de Ver\u00e3o Ib\u00e9rica teve lugar de 8 a 21 de julho de 2024 em Arcos de Valdevez, no norte de Portugal. O programa foi organizado pela Funda\u00e7\u00e3o Culturas Construtivas Tradicionais com a colabora\u00e7\u00e3o do INTBAU Portugal e do INTBAU Espanha; gra\u00e7as ao apoio de Richard H. Driehaus, do Munic\u00edpio de Arcos de Valdevez, [&hellip;]","og_url":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/","og_site_name":"Fundaci\u00f3n Culturas Constructivas Tradicionales","article_published_time":"2024-08-07T01:19:02+00:00","article_modified_time":"2024-10-02T17:15:40+00:00","og_image":[{"width":724,"height":542,"url":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos1.jpg","type":"image\/jpeg"}],"author":"Guillermo Gil","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Guillermo Gil","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/#article","isPartOf":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/"},"author":{"name":"Guillermo Gil","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#\/schema\/person\/2cff5e4776f5f0b01b837faf3fdc4664"},"headline":"Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024","datePublished":"2024-08-07T01:19:02+00:00","dateModified":"2024-10-02T17:15:40+00:00","mainEntityOfPage":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/"},"wordCount":1088,"publisher":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#organization"},"image":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos1.jpg","articleSection":["Escola de Ver\u00e3o Arcos 2024","Escola de Ver\u00e3o Ib\u00e9rica"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/","url":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/","name":"Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024 - Fundaci\u00f3n Culturas Constructivas Tradicionales","isPartOf":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/#primaryimage"},"image":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos1.jpg","datePublished":"2024-08-07T01:19:02+00:00","dateModified":"2024-10-02T17:15:40+00:00","breadcrumb":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/#primaryimage","url":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos1.jpg","contentUrl":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/08\/EscuelaArcos1.jpg","width":724,"height":542},{"@type":"BreadcrumbList","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/resultados-da-escola-de-verao-iberica-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/culturasconstructivas.org\/pt-pt\/fundacao-culturas-construtivas-tradicionais\/"},{"@type":"ListItem","position":2,"name":"Resultados da Escola de Ver\u00e3o Ib\u00e9rica 2024"}]},{"@type":"WebSite","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#website","url":"https:\/\/culturasconstructivas.org\/pt-pt\/","name":"Fundaci\u00f3n Culturas Constructivas Tradicionales","description":"","publisher":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/culturasconstructivas.org\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#organization","name":"Fundaci\u00f3n Culturas Constructivas Tradicionales","url":"https:\/\/culturasconstructivas.org\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2023\/10\/FUNDACAO-CULTURAS-CONSTRUTIVAS-Logo.png","contentUrl":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2023\/10\/FUNDACAO-CULTURAS-CONSTRUTIVAS-Logo.png","width":537,"height":290,"caption":"Fundaci\u00f3n Culturas Constructivas Tradicionales"},"image":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#\/schema\/person\/2cff5e4776f5f0b01b837faf3fdc4664","name":"Guillermo Gil","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/f6648e10de371ca3bbb6c2dfc0bd2f680bc092a6a74dfe978fb2fcc2bd9b3c27?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6648e10de371ca3bbb6c2dfc0bd2f680bc092a6a74dfe978fb2fcc2bd9b3c27?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6648e10de371ca3bbb6c2dfc0bd2f680bc092a6a74dfe978fb2fcc2bd9b3c27?s=96&d=mm&r=g","caption":"Guillermo Gil"},"url":"https:\/\/culturasconstructivas.org\/pt-pt\/author\/guillermo-gil\/"}]}},"_links":{"self":[{"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/posts\/12009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=12009"}],"version-history":[{"count":0,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/posts\/12009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/media\/11915"}],"wp:attachment":[{"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=12009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=12009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=12009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}