{"id":17585,"date":"2024-09-16T08:42:30","date_gmt":"2024-09-16T06:42:30","guid":{"rendered":"https:\/\/culturasconstructivas.org\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/"},"modified":"2025-01-31T10:09:20","modified_gmt":"2025-01-31T09:09:20","slug":"iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022","status":"publish","type":"page","link":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/","title":{"rendered":"III Congresso Internacional de Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais: Arquitetura Atemporal 2022"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":13022,"parent":17596,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_piecal_is_event":false,"_piecal_start_date":"","_piecal_end_date":"","_piecal_is_allday":false,"footnotes":""},"class_list":["post-17585","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>III Congresso Internacional de Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais: Arquitetura Atemporal 2022 - Fundaci\u00f3n Culturas Constructivas Tradicionales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"III Congresso Internacional de Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais: Arquitetura Atemporal 2022 - Fundaci\u00f3n Culturas Constructivas Tradicionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Culturas Constructivas Tradicionales\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-31T09:09:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/09\/Portada-JTBAU-2022_web.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"1754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\\\/edicoes-anteriores-do-congresso\\\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\\\/\",\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\\\/edicoes-anteriores-do-congresso\\\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\\\/\",\"name\":\"III Congresso Internacional de Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais: Arquitetura Atemporal 2022 - Fundaci\u00f3n Culturas Constructivas Tradicionales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\\\/edicoes-anteriores-do-congresso\\\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\\\/edicoes-anteriores-do-congresso\\\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Portada-JTBAU-2022_web.webp\",\"datePublished\":\"2024-09-16T06:42:30+00:00\",\"dateModified\":\"2025-01-31T09:09:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\\\/edicoes-anteriores-do-congresso\\\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\\\/edicoes-anteriores-do-congresso\\\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\\\/edicoes-anteriores-do-congresso\\\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Portada-JTBAU-2022_web.webp\",\"contentUrl\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Portada-JTBAU-2022_web.webp\",\"width\":1240,\"height\":1754},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\\\/edicoes-anteriores-do-congresso\\\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/fundacao-culturas-construtivas-tradicionais\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iniciativas\",\"item\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Congressos\",\"item\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Congresso Internacional sobre Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais\",\"item\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Edi\u00e7\u00f5es anteriores do Congresso\",\"item\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/iniciativas\\\/congressos\\\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\\\/edicoes-anteriores-do-congresso\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Protegido: III Congresso Internacional de Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais: Arquitetura Atemporal 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/\",\"name\":\"Fundaci\u00f3n Culturas Constructivas Tradicionales\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#organization\",\"name\":\"Fundaci\u00f3n Culturas Constructivas Tradicionales\",\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/FUNDACAO-CULTURAS-CONSTRUTIVAS-Logo.png\",\"contentUrl\":\"https:\\\/\\\/culturasconstructivas.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/FUNDACAO-CULTURAS-CONSTRUTIVAS-Logo.png\",\"width\":537,\"height\":290,\"caption\":\"Fundaci\u00f3n Culturas Constructivas Tradicionales\"},\"image\":{\"@id\":\"https:\\\/\\\/culturasconstructivas.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"III Congresso Internacional de Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais: Arquitetura Atemporal 2022 - Fundaci\u00f3n Culturas Constructivas Tradicionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/","og_locale":"pt_PT","og_type":"article","og_title":"III Congresso Internacional de Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais: Arquitetura Atemporal 2022 - Fundaci\u00f3n Culturas Constructivas Tradicionales","og_url":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/","og_site_name":"Fundaci\u00f3n Culturas Constructivas Tradicionales","article_modified_time":"2025-01-31T09:09:20+00:00","og_image":[{"width":1240,"height":1754,"url":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/09\/Portada-JTBAU-2022_web.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/","url":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/","name":"III Congresso Internacional de Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais: Arquitetura Atemporal 2022 - Fundaci\u00f3n Culturas Constructivas Tradicionales","isPartOf":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/#primaryimage"},"image":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/09\/Portada-JTBAU-2022_web.webp","datePublished":"2024-09-16T06:42:30+00:00","dateModified":"2025-01-31T09:09:20+00:00","breadcrumb":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/#primaryimage","url":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/09\/Portada-JTBAU-2022_web.webp","contentUrl":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2024\/09\/Portada-JTBAU-2022_web.webp","width":1240,"height":1754},{"@type":"BreadcrumbList","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/iii-congresso-internacional-de-construcao-arquitetura-e-urbanismo-tradicionais-arquitetura-atemporal-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/culturasconstructivas.org\/pt-pt\/fundacao-culturas-construtivas-tradicionais\/"},{"@type":"ListItem","position":2,"name":"Iniciativas","item":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/"},{"@type":"ListItem","position":3,"name":"Congressos","item":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/"},{"@type":"ListItem","position":4,"name":"Congresso Internacional sobre Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais","item":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/"},{"@type":"ListItem","position":5,"name":"Edi\u00e7\u00f5es anteriores do Congresso","item":"https:\/\/culturasconstructivas.org\/pt-pt\/iniciativas\/congressos\/congresso-internacional-sobre-construcao-arquitetura-e-urbanismo-tradicionais\/edicoes-anteriores-do-congresso\/"},{"@type":"ListItem","position":6,"name":"Protegido: III Congresso Internacional de Constru\u00e7\u00e3o, Arquitetura e Urbanismo Tradicionais: Arquitetura Atemporal 2022"}]},{"@type":"WebSite","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#website","url":"https:\/\/culturasconstructivas.org\/pt-pt\/","name":"Fundaci\u00f3n Culturas Constructivas Tradicionales","description":"","publisher":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/culturasconstructivas.org\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#organization","name":"Fundaci\u00f3n Culturas Constructivas Tradicionales","url":"https:\/\/culturasconstructivas.org\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2023\/10\/FUNDACAO-CULTURAS-CONSTRUTIVAS-Logo.png","contentUrl":"https:\/\/culturasconstructivas.org\/wp-content\/uploads\/2023\/10\/FUNDACAO-CULTURAS-CONSTRUTIVAS-Logo.png","width":537,"height":290,"caption":"Fundaci\u00f3n Culturas Constructivas Tradicionales"},"image":{"@id":"https:\/\/culturasconstructivas.org\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/pages\/17585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=17585"}],"version-history":[{"count":0,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/pages\/17585\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/pages\/17596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/media\/13022"}],"wp:attachment":[{"href":"https:\/\/culturasconstructivas.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=17585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}